{"id":29,"date":"2019-08-14T22:00:00","date_gmt":"2019-08-14T20:00:00","guid":{"rendered":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/"},"modified":"2019-08-14T22:00:00","modified_gmt":"2019-08-14T20:00:00","slug":"hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten","status":"publish","type":"post","link":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/","title":{"rendered":"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten"},"content":{"rendered":"<figure class=\"hoyre-image-wrapper\"><div class=\"hoyre-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2048\" src=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-scaled.jpg\" class=\"attachment-scaled size-scaled\" alt=\"\" style=\"object-position: 50% 50%\" srcset=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-scaled.jpg 2560w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-300x240.jpg 300w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-1024x819.jpg 1024w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-768x614.jpg 768w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-1536x1229.jpg 1536w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-2048x1638.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/figure><div id=\"hoyre-old-article-content-wrapper\"><p>  Bod\u00f8 H\u00f8yre har som m\u00e5l gj\u00f8re st\u00f8tteapparatet til ungdom bedre. Derfor har vi v\u00e6rt med p\u00e5 \u00e5 styrke Utekontakten i \u00e5rets kommunebudsjett. Utekontakten er et lavterskeltilbud for ungdom i alderen 13 til 20 \u00e5r. M\u00e5let er at unge skal kunne snakke med voksne som har forst\u00e5else for deres situasjon og kan hjelpe dem med \u00e5 f\u00e5 det bra i hverdagen.<\/p><p>For Utekontakten st\u00e5r opps\u00f8kende arbeid s\u00e6rlig fokus. Feltarbeidere m\u00f8ter ungdom der de er, for eksempel i Glasshuset, p\u00e5 skolen eller p\u00e5 fritidsklubben. Poenget er \u00e5 v\u00e6re p\u00e5 steder en vet at ungdom oppholder seg. Dette er absolutt et uvurderlig arbeid som bidrar til \u00e5 redde liv. Det er dessverre alt for mange ungdommer som har det vanskelig, og ellers ikke blir sett. Utekontakten er bare en av flere satsinger innen arbeid rettet spesielt mot ungdom som H\u00f8yre vil satse p\u00e5. <\/p><p>Skolehelsetjenesten er en treffsikker tjeneste, som n\u00e5r ut til mange. \u00c5 styrke skolehelsetjenesten har v\u00e6rt en nasjonal satsing fra regjeringen. Nylig har vi Bod\u00f8 Kommune styrket tilbudet med blant annet egne helser\u00e5dgivere for psykisk helse, og vi har vi v\u00e6rt tydelig p\u00e5 at dette er stillinger det er behov for at skal v\u00e6re nettopp her. Dette er erfaringer vi vil bygge videre p\u00e5 i neste periode.<\/p><p><br \/><\/p><\/div>\n<div class=\"tags\">\n\t<\/div>\n<div class=\"post-footer alignfull has-background block-editor-block-list__block\" data-align=full>\n\t<div class=\"post-footer-inner\">\n\t\t<h3>Relaterte artikler<\/h3>\n\t\t<div class=\"related-content\"><div class=\"is-card-hoyre\">\n\t<div class=\"teft-card hoyre-teft-card post-teft-card\">\n\t\t<a href=\"https:\/\/hoyre.no\/bodo\/aktuelt\/bodo-hoyres-nominasjonskomite\/\" class=\"teft-card__primary-action\">\n\n\t\t\t\t\t<div class=\"teft-card__media teft-card__media--16-9\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"500\" src=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2026\/04\/Bodo-Hoyre-nom.kom26.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2026\/04\/Bodo-Hoyre-nom.kom26.jpg 590w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2026\/04\/Bodo-Hoyre-nom.kom26-300x254.jpg 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/>\t\t<\/div>\n\t\t\n\t\t\t<div class=\"teft-card__content-wrapper\">\n\t\t\t\t<div class=\"teft-card__secondary\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"teft-card__meta\">\n\t\t\t\t\t\t\t\t\t<span class=\"post-date\">9. apr 2026<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"teft-card__primary\">\n\t\t\t\t\t<h2 class=\"teft-card__title\">Bod\u00f8 H\u00f8yres nominasjonskomite&nbsp;<span class=\"teft-card__primary-title-append\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\n\t<\/div><div class=\"is-card-hoyre\">\n\t<div class=\"teft-card hoyre-teft-card post-teft-card\">\n\t\t<a href=\"https:\/\/hoyre.no\/bodo\/aktuelt\/havet-plattformen\/\" class=\"teft-card__primary-action\">\n\n\t\t\t\t\t<div class=\"teft-card__media teft-card__media--16-9\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/04\/iStock-1218496388-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/04\/iStock-1218496388-768x512.jpg 768w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/04\/iStock-1218496388-300x200.jpg 300w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/04\/iStock-1218496388-1024x683.jpg 1024w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/04\/iStock-1218496388-1536x1024.jpg 1536w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/04\/iStock-1218496388-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t<\/div>\n\t\t\n\t\t\t<div class=\"teft-card__content-wrapper\">\n\t\t\t\t<div class=\"teft-card__secondary\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"teft-card__meta\">\n\t\t\t\t\t\t\t\t\t<span class=\"post-date\">22. sep 2023<\/span>\n\n\t\t\t\t\t\t\t\t\t<span class=\"post-category\">Ukategorisert<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"teft-card__primary\">\n\t\t\t\t\t<h2 class=\"teft-card__title\">Havet-plattformen&nbsp;<span class=\"teft-card__primary-title-append\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\n\t<\/div><div class=\"is-card-hoyre\">\n\t<div class=\"teft-card hoyre-teft-card post-teft-card\">\n\t\t<a href=\"https:\/\/hoyre.no\/bodo\/aktuelt\/bodo-hoyres-kandidater-til-kommunevalget-2023-2\/\" class=\"teft-card__primary-action\">\n\n\t\t\t\t\t<div class=\"teft-card__media teft-card__media--16-9\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-768x512.jpg 768w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-300x200.jpg 300w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-1024x683.jpg 1024w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-1536x1024.jpg 1536w, https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t<\/div>\n\t\t\n\t\t\t<div class=\"teft-card__content-wrapper\">\n\t\t\t\t<div class=\"teft-card__secondary\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"teft-card__meta\">\n\t\t\t\t\t\t\t\t\t<span class=\"post-date\">4. aug 2023<\/span>\n\n\t\t\t\t\t\t\t\t\t<span class=\"post-category\">Ukategorisert<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"teft-card__primary\">\n\t\t\t\t\t<h2 class=\"teft-card__title\">Bod\u00f8 H\u00f8yres kandidater til kommunevalget 2023&nbsp;<span class=\"teft-card__primary-title-append\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/a>\n\t<\/div>\n\n\t<\/div><\/div>\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"teft_cards_image_url":"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2020\/11\/m4dbm3wa_1-scaled.jpg","teft_cards_custom_pretitle":"","teft_cards_image_id":28,"teft_cards_image_focal_point_x":0,"teft_cards_image_focal_point_y":0,"teft_cards_title":"","teft_cards_excerpt":"","teft_show_chapters":false,"author_display_name":"Bod\u00f8 H\u00f8yre","footnotes":""},"category":[1],"post_tag":[],"hoyre-visibility":[],"article-type":[],"politician":[],"class_list":["post-29","post","type-post","status-publish","format-standard","hentry","category-ukategorisert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten - Bod\u00f8 H\u00f8yre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/\" \/>\n<meta property=\"og:site_name\" content=\"Bod\u00f8 H\u00f8yre\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-14T20:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten\",\"datePublished\":\"2019-08-14T20:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/\"},\"wordCount\":241,\"inLanguage\":\"nb-NO\"},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/\",\"url\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/\",\"name\":\"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten - Bod\u00f8 H\u00f8yre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/#website\"},\"datePublished\":\"2019-08-14T20:00:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/aktuelt\\\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Til hoyre.no\",\"item\":\"https:\\\/\\\/hoyre.no\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/#website\",\"url\":\"https:\\\/\\\/hoyre.no\\\/bodo\\\/\",\"name\":\"Bod\u00f8 H\u00f8yre\",\"description\":\"Bare enda et H\u00f8yres nettsteder-nettsted\",\"inLanguage\":\"nb-NO\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten - Bod\u00f8 H\u00f8yre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/","og_locale":"nb_NO","og_type":"article","og_title":"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten","og_url":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/","og_site_name":"Bod\u00f8 H\u00f8yre","article_published_time":"2019-08-14T20:00:00+00:00","og_image":[{"url":"https:\/\/hoyre.no\/content\/uploads\/sites\/148\/2023\/03\/Bilder-del-1-14-1024x683.jpg","width":"","height":"","type":""}],"twitter_card":"summary_large_image","twitter_misc":{"Ansl. lesetid":"1 minutt"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/#article","isPartOf":{"@id":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/"},"author":{"name":"","@id":""},"headline":"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten","datePublished":"2019-08-14T20:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/"},"wordCount":241,"inLanguage":"nb-NO"},{"@type":"NewsArticle","@id":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/","url":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/","name":"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten - Bod\u00f8 H\u00f8yre","isPartOf":{"@id":"https:\/\/hoyre.no\/bodo\/#website"},"datePublished":"2019-08-14T20:00:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hoyre.no\/bodo\/aktuelt\/hoyre_vil_styrke_skolehelsetjenesten_og_utekontakten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Til hoyre.no","item":"https:\/\/hoyre.no"},{"@type":"ListItem","position":2,"name":"Hjem","item":"https:\/\/hoyre.no\/bodo\/"},{"@type":"ListItem","position":3,"name":"H\u00f8yre vil styrke skolehelsetjenesten og Utekontakten"}]},{"@type":"WebSite","@id":"https:\/\/hoyre.no\/bodo\/#website","url":"https:\/\/hoyre.no\/bodo\/","name":"Bod\u00f8 H\u00f8yre","description":"Bare enda et H\u00f8yres nettsteder-nettsted","inLanguage":"nb-NO"}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Bod\u00f8 H\u00f8yre","distributor_original_site_url":"https:\/\/hoyre.no\/bodo","push-errors":false,"_links":{"self":[{"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/posts\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":0,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"wp:attachment":[{"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/category?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/post_tag?post=29"},{"taxonomy":"hoyre-visibility","embeddable":true,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/hoyre-visibility?post=29"},{"taxonomy":"article-type","embeddable":true,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/article-type?post=29"},{"taxonomy":"politician","embeddable":true,"href":"https:\/\/hoyre.no\/bodo\/wp-json\/wp\/v2\/politician?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}